{"id":29,"count":49,"description":"","link":"https:\/\/lasallecadiz.es\/mirandilla\/category\/generales\/","name":"Generales","slug":"generales","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}