{"id":2107,"date":"2017-05-29T09:03:48","date_gmt":"2017-05-29T09:03:48","guid":{"rendered":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15.jpg"},"modified":"2017-05-29T09:03:48","modified_gmt":"2017-05-29T09:03:48","slug":"virgen-diego-15","status":"inherit","type":"attachment","link":"https:\/\/lasallecadiz.es\/mirandilla\/virgen-diego-15\/","title":{"rendered":"Virgen Diego 15"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":""},"class_list":["post-2107","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15-169x300.jpg 169w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15.jpg 540w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":540,"height":960,"file":"2017\/05\/Virgen-Diego-15.jpg","sizes":{"thumbnail":{"file":"Virgen-Diego-15-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15-150x150.jpg"},"medium":{"file":"Virgen-Diego-15-169x300.jpg","width":169,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15-169x300.jpg"},"full":{"file":"Virgen-Diego-15.jpg","width":540,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/05\/Virgen-Diego-15.jpg","_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media\/2107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/comments?post=2107"}]}}