{"id":2251,"date":"2017-06-14T07:41:19","date_gmt":"2017-06-14T07:41:19","guid":{"rendered":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1.jpg"},"modified":"2017-06-14T07:42:23","modified_gmt":"2017-06-14T07:42:23","slug":"acto-despedida-6-epo-1","status":"inherit","type":"attachment","link":"https:\/\/lasallecadiz.es\/mirandilla\/2017\/06\/14\/acto-de-despedida-6o-e-p-o-en-nuestro-colegio-la-salle-mirandilla\/acto-despedida-6-epo-1\/#main","title":{"rendered":"Acto despedida 6 EPO 1"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":""},"class_list":["post-2251","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"Acto despedida 6 EPO 1\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1-300x225.jpg 300w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Acto despedida 6 EPO 1<\/p>\n"},"caption":{"rendered":"<p>Acto despedida 6 EPO 1<\/p>\n"},"alt_text":"Acto despedida 6 EPO 1","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":480,"height":360,"file":"2017\/06\/Acto-despedida-6-EPO-1.jpg","sizes":{"thumbnail":{"file":"Acto-despedida-6-EPO-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1-150x150.jpg"},"medium":{"file":"Acto-despedida-6-EPO-1-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1-300x225.jpg"},"full":{"file":"Acto-despedida-6-EPO-1.jpg","width":480,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2250,"source_url":"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2017\/06\/Acto-despedida-6-EPO-1.jpg","_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/comments?post=2251"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2250,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/2250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}