{"id":16735,"date":"2025-10-23T08:48:57","date_gmt":"2025-10-23T08:48:57","guid":{"rendered":"https:\/\/lasallecadiz.es\/mirandilla\/?p=16735"},"modified":"2025-10-23T08:50:47","modified_gmt":"2025-10-23T08:50:47","slug":"carmelo-el-espantapajaros-vuelve-a-sonreir","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/mirandilla\/2025\/10\/23\/carmelo-el-espantapajaros-vuelve-a-sonreir\/","title":{"rendered":"\u00a1Carmelo, el espantap\u00e1jaros, vuelve a sonre\u00edr!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"831\" height=\"1024\" data-id=\"16740\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-4-831x1024.jpeg\" alt=\"\" class=\"wp-image-16740\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-4-831x1024.jpeg 831w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-4-243x300.jpeg 243w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-4-768x946.jpeg 768w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-4.jpeg 1080w\" sizes=\"(max-width: 831px) 100vw, 831px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"838\" height=\"1024\" data-id=\"16738\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-3-838x1024.jpeg\" alt=\"\" class=\"wp-image-16738\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-3-838x1024.jpeg 838w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-3-246x300.jpeg 246w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-3-768x938.jpeg 768w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-3.jpeg 1080w\" sizes=\"(max-width: 838px) 100vw, 838px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"840\" height=\"1024\" data-id=\"16737\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-2-840x1024.jpeg\" alt=\"\" class=\"wp-image-16737\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-2-840x1024.jpeg 840w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-2-246x300.jpeg 246w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-2-768x937.jpeg 768w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-2.jpeg 1080w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"832\" height=\"1024\" data-id=\"16736\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-1.-2-832x1024.jpeg\" alt=\"\" class=\"wp-image-16736\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-1.-2-832x1024.jpeg 832w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-1.-2-244x300.jpeg 244w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-1.-2-768x945.jpeg 768w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/imagen-1.-2.jpeg 1080w\" sizes=\"(max-width: 832px) 100vw, 832px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16739\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo-1024x768.jpeg\" alt=\"\" class=\"wp-image-16739\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo-1024x768.jpeg 1024w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo-300x225.jpeg 300w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo-768x576.jpeg 768w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo-1536x1152.jpeg 1536w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2025\/10\/grupo.jpeg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>El alumnado de <strong>2\u00ba de Primaria<\/strong> ha vivido una experiencia muy especial: la creaci\u00f3n de su propio <strong>huerto escolar<\/strong>. Este proyecto ha llenado de vida y color una parte del colegio, convirti\u00e9ndose en un espacio donde aprender, experimentar y disfrutar del contacto con la naturaleza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83c\udf0d Aprendiendo a cuidar nuestro planeta<\/h3>\n\n\n\n<p>Durante varias semanas, los ni\u00f1os y ni\u00f1as han trabajado en distintas actividades relacionadas con el <strong>cuidado del medio ambiente<\/strong>. Han aprendido la importancia de <strong>ahorrar agua<\/strong>, de <strong>reducir el desperdicio<\/strong>, y de <strong>respetar la naturaleza<\/strong> que nos rodea.<br>A trav\u00e9s de juegos, charlas y peque\u00f1as investigaciones, comprendieron que cada gesto cuenta para proteger nuestro planeta. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83c\udf4e Sembrando conciencia y h\u00e1bitos saludables<\/h3>\n\n\n\n<p>Adem\u00e1s, el proyecto les permiti\u00f3 reflexionar sobre la importancia de una <strong>alimentaci\u00f3n equilibrada y responsable<\/strong>. Descubrieron el valor de las frutas y las hortalizas, aprendieron a reconocer las diferentes plantas del huerto y a entender de d\u00f3nde vienen los alimentos que comemos cada d\u00eda.<br>\u00a1Nada les hizo m\u00e1s ilusi\u00f3n que ver crecer las semillas que ellos mismos plantaron! \ud83c\udf3b\ud83d\udc69\u200d\ud83c\udf3e\ud83d\udc68\u200d\ud83c\udf3e<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc9a Un espacio para aprender y compartir<\/h3>\n\n\n\n<p>El huerto no solo es un rinc\u00f3n verde del colegio, sino tambi\u00e9n un <strong>aula viva<\/strong> donde el alumnado aprende de forma pr\u00e1ctica, colaborando y cuidando juntos su entorno. A trav\u00e9s del trabajo en equipo, han desarrollado valores como la <strong>responsabilidad<\/strong>, la <strong>paciencia<\/strong> y el <strong>respeto por la naturaleza<\/strong>.<\/p>\n\n\n\n<p>Y, por supuesto, no pod\u00eda faltar <strong>Carmelo, nuestro simp\u00e1tico espantap\u00e1jaros<\/strong>, que vuelve a sonre\u00edr rodeado de tanta alegr\u00eda y verdor. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83c\udf1e \u00a1Una experiencia que deja huella!<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alumnado de 2\u00ba de Primaria ha vivido una experiencia muy especial: la creaci\u00f3n de su propio huerto escolar. Este proyecto ha llenado de vida y color una parte del colegio, convirti\u00e9ndose en un espacio donde aprender, experimentar y disfrutar del contacto con la naturaleza. \ud83c\udf0d Aprendiendo a cuidar nuestro planeta Durante varias semanas, los &#8230; <a title=\"\u00a1Carmelo, el espantap\u00e1jaros, vuelve a sonre\u00edr!\" class=\"read-more\" href=\"https:\/\/lasallecadiz.es\/mirandilla\/2025\/10\/23\/carmelo-el-espantapajaros-vuelve-a-sonreir\/\" aria-label=\"Leer m\u00e1s sobre \u00a1Carmelo, el espantap\u00e1jaros, vuelve a sonre\u00edr!\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":25,"featured_media":16738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-16735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/16735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/comments?post=16735"}],"version-history":[{"count":1,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/16735\/revisions"}],"predecessor-version":[{"id":16741,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/16735\/revisions\/16741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media\/16738"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media?parent=16735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/categories?post=16735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/tags?post=16735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}