{"id":5351,"date":"2020-03-16T08:58:19","date_gmt":"2020-03-16T08:58:19","guid":{"rendered":"https:\/\/lasallecadiz.es\/mirandilla\/?p=5351"},"modified":"2024-04-15T18:21:01","modified_gmt":"2024-04-15T18:21:01","slug":"la-salle-cadiz-lasalleencasa","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/mirandilla\/2020\/03\/16\/la-salle-cadiz-lasalleencasa\/","title":{"rendered":"La Salle C\u00e1diz: #LaSalleEnCasa"},"content":{"rendered":"\n<p> <a href=\"https:\/\/www.facebook.com\/hashtag\/lasalleencasa?epa=HASHTAG\">#LaSalleEnCasa<\/a>\u00a0La Salle, como instituci\u00f3n responsable y comprometida con la sociedad, se suma con sus acciones al llamamiento de evitar toda acci\u00f3n que pueda contribuir a la propagaci\u00f3n del coronavirus. Juntos podremos conseguir que todo sea m\u00e1s f\u00e1cil.\u00a0<a href=\"https:\/\/www.facebook.com\/hashtag\/imagina?epa=HASHTAG\">#Imagina<\/a> <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"709\" height=\"960\" src=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2020\/03\/Circular-LA-SALLE.jpg\" alt=\"\" class=\"wp-image-5352\" srcset=\"https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2020\/03\/Circular-LA-SALLE.jpg 709w, https:\/\/lasallecadiz.es\/mirandilla\/wp-content\/uploads\/sites\/5\/2020\/03\/Circular-LA-SALLE-222x300.jpg 222w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#LaSalleEnCasa\u00a0La Salle, como instituci\u00f3n responsable y comprometida con la sociedad, se suma con sus acciones al llamamiento de evitar toda acci\u00f3n que pueda contribuir a la propagaci\u00f3n del coronavirus. Juntos podremos conseguir que todo sea m\u00e1s f\u00e1cil.\u00a0#Imagina<\/p>\n","protected":false},"author":3,"featured_media":5352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-5351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/comments?post=5351"}],"version-history":[{"count":1,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5351\/revisions"}],"predecessor-version":[{"id":5353,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5351\/revisions\/5353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media\/5352"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media?parent=5351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/categories?post=5351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/tags?post=5351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}