{"id":5728,"date":"2020-09-01T18:49:33","date_gmt":"2020-09-01T18:49:33","guid":{"rendered":"https:\/\/lasallecadiz.es\/mirandilla\/?p=5728"},"modified":"2024-04-15T18:20:36","modified_gmt":"2024-04-15T18:20:36","slug":"la-salle-lo-que-hemos-aprendido-una-reflexion-en-tiempos-del-covid-19-lasalle%f0%9f%92%99%f0%9f%92%9b","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/mirandilla\/2020\/09\/01\/la-salle-lo-que-hemos-aprendido-una-reflexion-en-tiempos-del-covid-19-lasalle%f0%9f%92%99%f0%9f%92%9b\/","title":{"rendered":"La Salle: Lo que hemos aprendido &#8211; Una reflexi\u00f3n + en tiempos del COVID-19 #LaSalle??"},"content":{"rendered":"\n<p>Varios alumnos de La Salle de Espa\u00f1a y Portugal han querido compartir su reflexi\u00f3n sobre lo vivido durante la pandemia. Las situaciones diferentes necesitan nuevas reflexiones y nuevas respuestas.<\/p>\n\n\n\n<p>Nada nos hac\u00eda prever que durante estos meses \u00edbamos a estar tan callados, tan confinados, tan aislados y distanciados de nuestras rutinas. <\/p>\n\n\n\n<p>Nada nos hac\u00eda prever que \u00edbamos a echar tanto de menos a los otros, que \u00edbamos a estar tan alejados y a la vez tan conectados. <\/p>\n\n\n\n<p>Las casas han sido escuelas, oficinas, talleres de cocina, gimnasios, teatros improvisados y espacios responsables llenos de vida. <\/p>\n\n\n\n<p>Hemos aplaudido a los que han dado la cara por nosotros, hemos sufrido con los que han tenido que despedirse antes de tiempo y hemos unido nuestro coraz\u00f3n al coraz\u00f3n del mundo. <\/p>\n\n\n\n<p>Despu\u00e9s de este tiempo, solamente nos queda confiar y valorar las cosas m\u00e1s sencillas. Te quiero, creo en ti, gracias, estoy aqu\u00ed, cu\u00eddate, tengo ganas de verte&#8230; Las cosas realmente importantes en la vida no necesitan muchas palabras. <\/p>\n\n\n\n<p>Esta lecci\u00f3n solo necesita un coraz\u00f3n como el tuyo y la alegr\u00eda de seguir caminando JUNTOS.<\/p>\n\n\n\n<p>Y tu, \u00bfQuieres? \u00a1Somos La Salle!<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube aligncenter wp-block-embed is-type-rich is-provider-gestor-del-servicio wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Lo que hemos aprendido - Una reflexi\u00f3n + en tiempos del COVID-19 #LaSalle\ud83d\udc99\ud83d\udc9b\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Qqk9dvBvRxQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Varios alumnos de La Salle de Espa\u00f1a y Portugal han querido compartir su reflexi\u00f3n sobre lo vivido durante la pandemia. Las situaciones diferentes necesitan nuevas reflexiones y nuevas respuestas. Nada nos hac\u00eda prever que durante estos meses \u00edbamos a estar tan callados, tan confinados, tan aislados y distanciados de nuestras rutinas. Nada nos hac\u00eda prever &#8230; <a title=\"La Salle: Lo que hemos aprendido &#8211; Una reflexi\u00f3n + en tiempos del COVID-19 #LaSalle??\" class=\"read-more\" href=\"https:\/\/lasallecadiz.es\/mirandilla\/2020\/09\/01\/la-salle-lo-que-hemos-aprendido-una-reflexion-en-tiempos-del-covid-19-lasalle%f0%9f%92%99%f0%9f%92%9b\/\" aria-label=\"Leer m\u00e1s sobre La Salle: Lo que hemos aprendido &#8211; Una reflexi\u00f3n + en tiempos del COVID-19 #LaSalle??\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":5729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-5728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/comments?post=5728"}],"version-history":[{"count":3,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5728\/revisions"}],"predecessor-version":[{"id":6600,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/posts\/5728\/revisions\/6600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media\/5729"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/media?parent=5728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/categories?post=5728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/mirandilla\/wp-json\/wp\/v2\/tags?post=5728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}