{"id":10975,"date":"2023-02-14T08:45:17","date_gmt":"2023-02-14T08:45:17","guid":{"rendered":"https:\/\/lasallecadiz.es\/prueba1\/?p=10975"},"modified":"2025-10-10T08:10:37","modified_gmt":"2025-10-10T08:10:37","slug":"encuentro-la-salle-accion-social","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/vina\/encuentro-la-salle-accion-social\/","title":{"rendered":"Encuentro La Salle Acci\u00f3n Social"},"content":{"rendered":"\n<p>II Encuentro La Salle Acci\u00f3n Social \u201cTodo est\u00e1 conectado\u201d (Laudato Si\u2019 91)<\/p>\n\n\n\n<p><br>Con el objetivo de seguir trabajando de forma conjunta para hacer frente a los desaf\u00edos sociales y ambientales, La Salle Acci\u00f3n Social en Andaluc\u00eda celebr\u00f3 con \u00e9xito su II Encuentro bajo el t\u00edtulo \u00abTodo est\u00e1 conectado\u00bb (Laudato si\u2019 91). El encuentro, que tuvo lugar el pasado 11 de febrero en el Hogar La Salle de Jerez de la Frontera, cont\u00f3 con la presencia de D. Isaac S\u00e1nchez Jim\u00e9nez, asesor experto en<br>ecolog\u00eda e inclusi\u00f3n, para llevar a cabo un seminario sobre la conexi\u00f3n entre la naturaleza, los dem\u00e1s seres humanos y el mundo que nos rodea.<br>Alrededor de setenta personas de diferentes entidades y personas voluntarias, miembros de las comunidades lasalianas y coordinadores de justicia, solidaridad y paz de las Obras Educativas, entre otras, se reunieron para reflexionar sobre la responsabilidad que tenemos como seres humanos de trabajar juntos para crear un futuro m\u00e1s justo y sostenible para todas las criaturas del planeta.<br>Durante el encuentro, se realizaron c\u00edrculos de escucha, talleres y otras actividades para profundizar en los objetivos derivados de la enc\u00edclica Laudato si\u2019. Se ofrecieron oportunidades para compartir experiencias, conocimientos y conexiones entre el personal vinculado a las Obras Socioeducativas de La Salle en Andaluc\u00eda, delegados de la ONGD PROYDE, coordinadores de justicia, solidaridad y paz de los centros educativos La Salle, miembros de las comunidades lasalianas, y otras personas invitadas.<br>El objetivo principal de este encuentro fue reflexionar acerca de la responsabilidad que todos tenemos, como seres humanos, para trabajar juntos para hacer frente a los desaf\u00edos sociales y ambientales y crear un futuro m\u00e1s justo y sostenible para todas las criaturas del planeta. En este sentido, tambi\u00e9n se busc\u00f3 fomentar la colaboraci\u00f3n y el trabajo en red entre las distintas entidades y personas implicadas en la acci\u00f3n social en Andaluc\u00eda y Melilla.<br>El II Encuentro La Salle Acci\u00f3n Social ha sido una oportunidad para recordar que la sociedad est\u00e1 interconectada y que juntos somos m\u00e1s fuertes para conseguir un mundo mejor. La Salle seguir\u00e1 trabajando para seguir transformando la realidad y seguir siendo una voz activa para la mejora de nuestro medio y de la sociedad.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"10992\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-768x1024.jpg\" alt=\"\" class=\"wp-image-10992\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-1536x2048.jpg 1536w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111956-2-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"10991\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-768x1024.jpg\" alt=\"\" class=\"wp-image-10991\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-1536x2048.jpg 1536w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_113729-1-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10990\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-1024x768.jpg\" alt=\"\" class=\"wp-image-10990\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-1024x768.jpg 1024w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-300x225.jpg 300w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-768x576.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-1536x1152.jpg 1536w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_111153-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"10989\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-1024x768.jpg\" alt=\"\" class=\"wp-image-10989\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-1024x768.jpg 1024w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-300x225.jpg 300w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-768x576.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-1536x1152.jpg 1536w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134404-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-1024x768.jpg\" alt=\"\" class=\"wp-image-10987\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-1024x768.jpg 1024w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-300x225.jpg 300w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-768x576.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-1536x1152.jpg 1536w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/IMG_20230211_134817-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>II Encuentro La Salle Acci\u00f3n Social \u201cTodo est\u00e1 conectado\u201d (Laudato Si\u2019 91) Con el objetivo de seguir trabajando de forma conjunta para hacer frente a los desaf\u00edos sociales y ambientales, La Salle Acci\u00f3n Social en Andaluc\u00eda celebr\u00f3 con \u00e9xito su II Encuentro bajo el t\u00edtulo \u00abTodo est\u00e1 conectado\u00bb (Laudato si\u2019 91). El encuentro, que tuvo &#8230; <a title=\"Encuentro La Salle Acci\u00f3n Social\" class=\"read-more\" href=\"https:\/\/lasallecadiz.es\/vina\/encuentro-la-salle-accion-social\/\" aria-label=\"Leer m\u00e1s sobre Encuentro La Salle Acci\u00f3n Social\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":123482,"featured_media":10978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-10975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/10975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/users\/123482"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/comments?post=10975"}],"version-history":[{"count":3,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/10975\/revisions"}],"predecessor-version":[{"id":10994,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/10975\/revisions\/10994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media\/10978"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media?parent=10975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/categories?post=10975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/tags?post=10975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}