{"id":11000,"date":"2023-02-18T12:00:00","date_gmt":"2023-02-18T12:00:00","guid":{"rendered":"https:\/\/lasallecadiz.es\/prueba1\/?p=11000"},"modified":"2025-10-10T08:10:36","modified_gmt":"2025-10-10T08:10:36","slug":"practicas-en-laboratorio","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/vina\/practicas-en-laboratorio\/","title":{"rendered":"Pr\u00e1cticas en Laboratorio"},"content":{"rendered":"\n<p>El alumnado de #1BachilleratoCiencias dentro de su curriculum escolar, en esta semana y coincidiendo con la Semana de la Mujer y la Ciencia, est\u00e1 comenzando las pr\u00e1cticas en el Laboratorio, No hay mejor manera de aprendizaje que vivir la experiencia. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11004\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-13.10.52-768x1024.jpg\" alt=\"\" class=\"wp-image-11004\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-13.10.52-768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-13.10.52-225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-13.10.52-1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-13.10.52.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11001\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-768x1024.jpg\" alt=\"\" class=\"wp-image-11001\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11003\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16--768x1024.jpg\" alt=\"\" class=\"wp-image-11003\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16--768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16--225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16--1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"11002\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-10.45.37-768x1024.jpg\" alt=\"\" class=\"wp-image-11002\" srcset=\"https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-10.45.37-768x1024.jpg 768w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-10.45.37-225x300.jpg 225w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-10.45.37-1152x1536.jpg 1152w, https:\/\/lasallecadiz.es\/vina\/wp-content\/uploads\/sites\/4\/2023\/02\/Imagen-de-WhatsApp-2023-02-16-a-las-10.45.37.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El alumnado de #1BachilleratoCiencias dentro de su curriculum escolar, en esta semana y coincidiendo con la Semana de la Mujer y la Ciencia, est\u00e1 comenzando las pr\u00e1cticas en el Laboratorio, No hay mejor manera de aprendizaje que vivir la experiencia.<\/p>\n","protected":false},"author":123482,"featured_media":11005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-11000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/users\/123482"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/comments?post=11000"}],"version-history":[{"count":1,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11000\/revisions"}],"predecessor-version":[{"id":11006,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11000\/revisions\/11006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media\/11005"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media?parent=11000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/categories?post=11000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/tags?post=11000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}