{"id":11109,"date":"2023-05-29T12:27:10","date_gmt":"2023-05-29T12:27:10","guid":{"rendered":"https:\/\/lasallecadiz.es\/prueba1\/?p=11109"},"modified":"2025-10-10T08:10:35","modified_gmt":"2025-10-10T08:10:35","slug":"imposicion-de-becas-e-insignias-2023","status":"publish","type":"post","link":"https:\/\/lasallecadiz.es\/vina\/imposicion-de-becas-e-insignias-2023\/","title":{"rendered":"Imposici\u00f3n de Becas e Insignias 2023"},"content":{"rendered":"\n<p>El pasado viernes tuvimos el acto de entrega de Becas e Insignias a los alumnos finalistas de este a\u00f1o. Fue un acto muy emotivo empezando a las 19:00h. con una Eucarist\u00eda de Acci\u00f3n de Gracias oficiada por el Vicario parroquial de la Parroquia San Lorenzo, Padre Juan Pablo. Despu\u00e9s del acto lit\u00fargico,  en el patio del Centro tuvo lugar la ultima lecci\u00f3n que la imparti\u00f3 la profesora de franc\u00e9s, Paola, seguidamente los alumnos hicieron sus discursos de despedida y la entrega de las becas e insignias. Terminamos el acto con la Entrega del premio Hno Abd\u00f3n y con el descubrimiento de la Orla 2023. Para despedirnos tuvimos un \u00e1gape en el patio . Muchas gracias a todos\/as<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11120\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/1.jpg\" alt=\"\" class=\"wp-image-11120\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11118\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/2.jpg\" alt=\"\" class=\"wp-image-11118\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11117\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/3.jpg\" alt=\"\" class=\"wp-image-11117\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11115\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/4.jpg\" alt=\"\" class=\"wp-image-11115\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11119\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/5.jpg\" alt=\"\" class=\"wp-image-11119\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11114\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/6.jpg\" alt=\"\" class=\"wp-image-11114\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11116\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/7.jpg\" alt=\"\" class=\"wp-image-11116\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11121\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/8.jpg\" alt=\"\" class=\"wp-image-11121\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11122\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/9.jpg\" alt=\"\" class=\"wp-image-11122\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11123\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/10.jpg\" alt=\"\" class=\"wp-image-11123\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11124\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/11.jpg\" alt=\"\" class=\"wp-image-11124\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"142\" data-id=\"11125\" src=\"https:\/\/lasallecadiz.es\/prueba1\/wp-content\/uploads\/sites\/4\/2023\/05\/12.jpg\" alt=\"\" class=\"wp-image-11125\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes tuvimos el acto de entrega de Becas e Insignias a los alumnos finalistas de este a\u00f1o. Fue un acto muy emotivo empezando a las 19:00h. con una Eucarist\u00eda de Acci\u00f3n de Gracias oficiada por el Vicario parroquial de la Parroquia San Lorenzo, Padre Juan Pablo. Despu\u00e9s del acto lit\u00fargico, en el patio &#8230; <a title=\"Imposici\u00f3n de Becas e Insignias 2023\" class=\"read-more\" href=\"https:\/\/lasallecadiz.es\/vina\/imposicion-de-becas-e-insignias-2023\/\" aria-label=\"Leer m\u00e1s sobre Imposici\u00f3n de Becas e Insignias 2023\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":123482,"featured_media":11110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-11109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/users\/123482"}],"replies":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/comments?post=11109"}],"version-history":[{"count":1,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11109\/revisions"}],"predecessor-version":[{"id":11126,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/posts\/11109\/revisions\/11126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media\/11110"}],"wp:attachment":[{"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/media?parent=11109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/categories?post=11109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasallecadiz.es\/vina\/wp-json\/wp\/v2\/tags?post=11109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}